{"id":23752,"date":"2025-07-10T17:11:47","date_gmt":"2025-07-10T15:11:47","guid":{"rendered":"http:\/\/www.noserlight.ch\/home\/?p=16303&#038;lang=de"},"modified":"2025-07-18T01:08:47","modified_gmt":"2025-07-17T23:08:47","slug":"einbruchschutz-ploetzliches-licht-schreckt-ab-2","status":"publish","type":"post","link":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/","title":{"rendered":"Einbruchschutz &#8211;  Licht schreckt ab"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; padding_top=&#8220;37&#8243; padding_bottom=&#8220;57&#8243; css=&#8220;.vc_custom_1696619164028{background-color: #ffffff !important;}&#8220; z_index=&#8220;&#8220;][vc_column][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LEDStrahler_Download.pdf\" target=\"_blank\" rel=\"noopener\">LED SCHEINWERFER UND LED FLUTER<\/a> F\u00dcR MEHR SICHERHEIT<\/h3>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;20px&#8220;][vc_column_text]Prinzipiell sollte Einbrechern das Handwerk schwer gemacht werden. Zum Schutz vor Ungebetenen bietet der Markt eine riesige Bandbreite verschiedener Massnahmen. Eine eigenst\u00e4ndige, helle Sicherheitsbeleuchtung, die unerwartet aufleuchtet, ist Bestandteil jedes Sicherheitskonzeptes.<\/p>\n<p><strong>Zus\u00e4tzliche Sicherheitsbeleuchtung<\/strong><\/p>\n<p>F\u00fcr eine zus\u00e4tzliche Sicherheitsbeleuchtung werden zum Beispiel unter dem Dachfirst <a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LEDStrahler_Download.pdf\" target=\"_blank\" rel=\"noopener\">Strahler oder Scheinwerfer<\/a> montiert. Mit mehreren Bewegungsmeldern verbunden und in einer Reihe geschaltet oder mit anderen elektronischen Sicherheitseinrichtungen kombiniert, sollten sie den Bereich rund ums Haus m\u00f6glichst l\u00fcckenlos ausleuchten.<\/p>\n<p>Das Licht muss immer vom Haus weg gerichtet sein. Es eignen sich auch nur Lampen und Leuchten, die nach dem Einschalten sofort den vollen Lichtstrom (also 100% Licht) abgeben, wie\u00a0LED oder Halogen. LED sind jedoch auf Grund ihrer Lebensdauer und wegen des viel niedrigen Stromverbrauches klar zu bevorzugen.<\/p>\n<p>Einen gewissen Schutz bietet auch die gute allgemeine Aussenbeleuchtung, sofern einige Leuchten als Dauerlicht und mehrere Leuchten \u00fcber einen Bewegungsmelder geschaltet werden. Eine \u00fcberaus wirkungsvolle Reaktion auf verd\u00e4chtige Ger\u00e4usche ist auch das Einschalten der gesamten Aussenbeleuchtung \u00fcber einen zentralen Schalter im Wohn- oder Schlafbereich.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; padding_top=&#8220;57&#8243; padding_bottom=&#8220;57&#8243; z_index=&#8220;&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_empty_space height=&#8220;10px&#8220;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><a itemprop=\"url\" href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LEDStrahler_Download.pdf\" target=\"\" class=\"q_icon_link\"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-book qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/a><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">KATALOG<\/h3><p style='color: #000000'><\/p><a itemprop='url' class='icon_with_title_link' href='https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LEDStrahler_Download.pdf' target='_self' style=''>LED Strahler und LED Flutlichter in der \u00dcbersicht<\/a><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_empty_space height=&#8220;10px&#8220;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/kontakt\/\" target=\"\" class=\"q_icon_link\"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-eye qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/a><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">Live ansehen<\/h3><p style=''><\/p><a itemprop='url' class='icon_with_title_link' href='https:\/\/www.noserlight.ch\/home\/kontakt\/' target='_self' style=''>Sieh dir unsere NOSER Qualit\u00e4ts-Brand Sortiment an LED live in unserem Store an.<\/a><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_empty_space height=&#8220;10px&#8220;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/shop\/\" target=\"\" class=\"q_icon_link\"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-cart-plus qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/a><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">Zum Online-Shop<\/h3><p style=''><\/p><a itemprop='url' class='icon_with_title_link' href='https:\/\/www.noserlight.ch\/shop\/' target='_self' style=''>Du weisst was du brauchst? Dann geht es hier zu unserem Online-Shop mit den besten Deals f\u00fcr dein perfektes LED Licht-Projekt.<\/a><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; padding_top=&#8220;57&#8243; padding_bottom=&#8220;57&#8243; css=&#8220;.vc_custom_1695937585721{background-color: #ffffff !important;}&#8220; z_index=&#8220;&#8220;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">AKTUELL<\/h2>\n<p>[\/vc_column_text][vc_separator type=&#8220;small&#8220; position=&#8220;center&#8220; down=&#8220;45&#8243; up=&#8220;7&#8243;]\n<div class='latest_post_holder boxes three_columns three_rows' >\n    <ul>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/sparlampenersatz_fl_ersatz\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"292\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/02\/ID111_LED_T8_Kat-539x292.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/sparlampenersatz_fl_ersatz\/\">ERSATZ F\u00dcR FL-R\u00d6HREN UND SPARLAMPEN<\/a><\/h5>\n                            <p class=\"excerpt\">Suchst du Ersatz f\u00fcr Sparlampen und FL-R\u00f6hren die verboten wurden? Wir bieten ihn. Egal ob f\u00fcrs Facility Management, Ers...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/licht-fuer-wege-und-treppen-im-freien\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-300x169.jpg 300w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-1024x576.jpg 1024w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-768x432.jpg 768w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-1536x864.jpg 1536w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-700x394.jpg 700w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen.jpg 1920w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/licht-fuer-wege-und-treppen-im-freien\/\">Licht f\u00fcr Wege und Treppen im Freien<\/a><\/h5>\n                            <p class=\"excerpt\">Wegbeleuchtung und Treppenbeleuchtung. Wege zum und um das Haus, den Kellereingang oder zur Garage sollten gut beleuchte...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/warum-gutes-licht-der-schluessel-zum-lernerfolg-ist\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2024\/08\/HCL_TagesNachtzyklusLichtLED-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2024\/08\/HCL_TagesNachtzyklusLichtLED-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2024\/08\/HCL_TagesNachtzyklusLichtLED-300x169.jpg 300w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2024\/08\/HCL_TagesNachtzyklusLichtLED-1024x576.jpg 1024w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2024\/08\/HCL_TagesNachtzyklusLichtLED-768x432.jpg 768w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2024\/08\/HCL_TagesNachtzyklusLichtLED-1536x864.jpg 1536w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2024\/08\/HCL_TagesNachtzyklusLichtLED-700x394.jpg 700w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2024\/08\/HCL_TagesNachtzyklusLichtLED.jpg 1920w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/warum-gutes-licht-der-schluessel-zum-lernerfolg-ist\/\">Warum gutes Licht der Schl\u00fcssel ist.<\/a><\/h5>\n                            <p class=\"excerpt\">Licht ist mehr als nur Helligkeit. Es beeinflusst, wie wir uns f\u00fchlen, denken und arbeiten. In einer Welt, die zunehmend...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-300x169.jpg 300w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-1024x576.jpg 1024w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-768x432.jpg 768w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-1536x864.jpg 1536w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-700x394.jpg 700w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg 1920w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\">Einbruchschutz &#8211;  Licht schreckt ab<\/a><\/h5>\n                            <p class=\"excerpt\">F\u00fcr eine zus\u00e4tzliche Sicherheitsbeleuchtung werden zum Beispiel unter dem Dachfirst Strahler oder Scheinwerfer montiert....<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/schutzklassen\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/IP_Schutzarten637x320-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/IP_Schutzarten637x320-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/IP_Schutzarten637x320-570x320.jpg 570w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/schutzklassen\/\">Schutzklassen<\/a><\/h5>\n                            <p class=\"excerpt\">LEUCHTEN UND SCHUTZKLASSEN\r\nSchutzklassen dienen in der Elektrotechnik der Einteilung und Kennzeichnung von elektrischen...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/welcome-licht-fuer-den-hauseingang\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/03\/NOSERLIGHT_LichtfuerdenEingang-2-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/welcome-licht-fuer-den-hauseingang\/\">Welcome! Licht f\u00fcr den Hauseingang<\/a><\/h5>\n                            <p class=\"excerpt\">Licht im Eingangsbereich und an der Haust\u00fcr ist doppelt wichtig: Es wirkt einladend und sorgt......<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/erzielen-sie-raumlicht-wirkung\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-300x169.jpg 300w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-1024x576.jpg 1024w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-768x432.jpg 768w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-1536x864.jpg 1536w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-700x394.jpg 700w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V.jpg 1920w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/erzielen-sie-raumlicht-wirkung\/\">Erziele (Raumlicht-)Wirkung!<\/a><\/h5>\n                            <p class=\"excerpt\">Weil indirektes Licht diffus leuchte, kaum Schatten wirft, sich optimal im Raum verteilt und nicht blendet, eignet es si...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/das-smarte-lichtfenster\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/02\/NOSERLIGHT_LEDPanelOffice-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/das-smarte-lichtfenster\/\">Das smarte Lichtfenster<\/a><\/h5>\n                            <p class=\"excerpt\">Die Beleuchtung mit Led Panel sind mittlerweile in aller Munde. Unser Standard Led Panel verf\u00fcgen......<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/tipps-fuer-die-private-lichtplanung\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/02\/suite_ambient-980x500-1-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/tipps-fuer-die-private-lichtplanung\/\">Tipps f\u00fcr die private Lichtplanung<\/a><\/h5>\n                            <p class=\"excerpt\">Essen, lesen, fernsehen, arbeiten oder entspannen \u2013 das Beispiel Wohnzimmer zeigt, dass die Beleuchtung vielen......<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n        <\/ul>\n<\/div>[\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;full_width&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220;][vc_column][vc_empty_space height=&#8220;20px&#8220;][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;full_width&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; z_index=&#8220;&#8220; padding_top=&#8220;57&#8243;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">KONTAKT<\/h2>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;20px&#8220;][vc_separator type=&#8220;small&#8220; position=&#8220;center&#8220; down=&#8220;38&#8243; up=&#8220;7&#8243;][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; padding_top=&#8220;20&#8243; padding_bottom=&#8220;57&#8243; z_index=&#8220;&#8220;][vc_column width=&#8220;1\/4&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-clock-o qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">\u00d6FFNUNGSZEITEN<\/h3><p style=''><\/p><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Mo. &#8211; Fr.<br \/>\n<\/strong>07.30 &#8211; 12.00, 13.15 &#8211; 17.30Uhr<br \/>\n<strong>Sa. <\/strong>09.00 &#8211; 16.00Uhr, durchgehend<\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;30px&#8220;][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-home qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">BESUCHE UNS<\/h3><p style=''><\/p><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\">\u00a0Erlebe unsere Produkte<br \/>\nOttenbacherstrasse 25<br \/>\nCH-8909 Zwillikon\/Affoltern a.A.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;30px&#8220;][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-phone qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">RUF AN ODER SCHREIB' UNS<\/h3><p style=''><\/p><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\">Phone:\u00a0+41 44 701 81 81<br \/>\nEmail:\u00a0<a href=\"mailto:info@noserlight.ch.ch\">info@noserlight.ch.ch<\/a><\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;30px&#8220;][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-thumbs-o-up qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">FOLGE UNS<\/h3><p style=''><\/p><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\">Instagram: <a href=\"https:\/\/www.instagram.com\/noserlight\/\">@noserlight.ch<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/noserlight\/\">Facebook: Bruchsch Liecht?<\/a><\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;30px&#8220;][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; padding_top=&#8220;57&#8243; padding_bottom=&#8220;57&#8243; z_index=&#8220;&#8220; background_color=&#8220;#ffffff&#8220;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">TAKE A RIDE TO THE LIGHT SIDE (DER WEG ZU UNS)<\/h2>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;20px&#8220;][vc_separator type=&#8220;small&#8220; position=&#8220;center&#8220; down=&#8220;38&#8243; up=&#8220;7&#8243;][vc_gmaps link=&#8220;#E-8_JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxMW0xOCUyMTFtMTIlMjExbTMlMjExZDI3MDYuMzIwNzA5NTcxMTA4NiUyMTJkOC40MzkxODIzMTU4NTE0MjclMjEzZDQ3LjI4ODUzMTk3OTE2NDk0JTIxMm0zJTIxMWYwJTIxMmYwJTIxM2YwJTIxM20yJTIxMWkxMDI0JTIxMmk3NjglMjE0ZjEzLjElMjEzbTMlMjExbTIlMjExczB4NDc5MDA2MThlMzI1OTZiNSUyNTNBMHgyN2JmNmNkMmI5MjdkMWUlMjEyc05vc2VyJTI1MjBMaWdodCUyNTIwQUclMjE1ZTAlMjEzbTIlMjExc2RlJTIxMnNjaCUyMTR2MTY3Mzc4OTQwMzg0MCUyMTVtMiUyMTFzZGUlMjEyc2NoJTIyJTIwd2lkdGglM0QlMjI2MDAlMjIlMjBoZWlnaHQlM0QlMjI0NTAlMjIlMjBzdHlsZSUzRCUyMmJvcmRlciUzQTAlM0IlMjIlMjBhbGxvd2Z1bGxzY3JlZW4lM0QlMjIlMjIlMjBsb2FkaW5nJTNEJTIybGF6eSUyMiUyMHJlZmVycmVycG9saWN5JTNEJTIybm8tcmVmZXJyZXItd2hlbi1kb3duZ3JhZGUlMjIlM0UlM0MlMkZpZnJhbWUlM0U=&#8220;][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;full_width&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220;][vc_column][vc_empty_space][vc_separator type=&#8220;normal&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>F\u00fcr eine zus\u00e4tzliche Sicherheitsbeleuchtung werden zum Beispiel unter dem Dachfirst Strahler oder Scheinwerfer montiert. Mit mehreren Bewegungsmeldern verbunden und in einer Reihe geschaltet oder mit anderen elektronischen Sicherheitseinrichtungen kombiniert, sollten sie den Bereich rund ums Haus m\u00f6glichst l\u00fcckenlos ausleuchten.<\/p>\n","protected":false},"author":2,"featured_media":27151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74,78,73,836,867,948],"tags":[1107,935,1488,1490,2199,1084,1109,2200,2201,2202,1091,1437,1492,1438,1493,1439],"class_list":["post-23752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architectural-lighting-licht-fuer-architektur","category-facility-lighting-licht-fuer-immobilien-und-facility-management","category-home-lighting-licht-fuer-zuhause","category-noser","category-professionelle-led-beleuchtung","category-tipps-und-tricks","tag-led-aussenbeleuchtung","tag-led-aussenlampen","tag-led-bewegungsmelder","tag-led-einbruchschutz","tag-led-fluter","tag-led-flutlicht","tag-led-fuer-aussen","tag-led-hallenbeleuchtung","tag-led-parkplatzbeleuchtung","tag-led-platzbeleuchtung","tag-led-strahler","tag-led-strahler-mit-abnehmbarem-akku","tag-led-strahler-mit-bewegungsmelder","tag-led-strahler-mit-powerbank","tag-led-strahler-mit-sensor","tag-led-strahler-mobil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Einbruchschutz - Licht schreckt ab - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\" \/>\r\n<meta property=\"og:locale\" content=\"de_DE\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Einbruchschutz - Licht schreckt ab - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\" \/>\r\n<meta property=\"og:description\" content=\"F\u00fcr eine zus\u00e4tzliche Sicherheitsbeleuchtung werden zum Beispiel unter dem Dachfirst Strahler oder Scheinwerfer montiert. Mit mehreren Bewegungsmeldern verbunden und in einer Reihe geschaltet oder mit anderen elektronischen Sicherheitseinrichtungen kombiniert, sollten sie den Bereich rund ums Haus m\u00f6glichst l\u00fcckenlos ausleuchten.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noserlight\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-07-10T15:11:47+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-07-17T23:08:47+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Nosi\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nosi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\"},\"author\":{\"name\":\"Nosi\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/#\/schema\/person\/cd72adab091f0db04aef8e43d9b74611\"},\"headline\":\"Einbruchschutz &#8211; Licht schreckt ab\",\"datePublished\":\"2025-07-10T15:11:47+00:00\",\"dateModified\":\"2025-07-17T23:08:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\"},\"wordCount\":1291,\"publisher\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg\",\"keywords\":[\"LED Aussenbeleuchtung\",\"LED Aussenlampen\",\"LED Bewegungsmelder\",\"LED Einbruchschutz\",\"LED Fluter\",\"LED Flutlicht\",\"LED f\u00fcr Aussen\",\"LED Hallenbeleuchtung\",\"LED Parkplatzbeleuchtung\",\"LED Platzbeleuchtung\",\"LED Strahler\",\"LED Strahler mit abnehmbarem Akku\",\"LED Strahler mit Bewegungsmelder\",\"LED Strahler mit Powerbank\",\"LED Strahler mit Sensor\",\"LED Strahler mobil\"],\"articleSection\":[\"Architectural Lighting\",\"Facility Lighting\",\"Home Lighting - Licht f\u00fcr Zuhause\",\"NOSER\",\"Professionelle LED Beleuchtung\",\"Tipps und Tricks\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\",\"url\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\",\"name\":\"Einbruchschutz - Licht schreckt ab - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\",\"isPartOf\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg\",\"datePublished\":\"2025-07-10T15:11:47+00:00\",\"dateModified\":\"2025-07-17T23:08:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#primaryimage\",\"url\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg\",\"contentUrl\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.noserlight.ch\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einbruchschutz &#8211; Licht schreckt ab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/#website\",\"url\":\"https:\/\/www.noserlight.ch\/home\/\",\"name\":\"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\",\"description\":\"Bruchsch Liecht? D\u00e4 Nosi h\u00e4t&#039;s!\",\"publisher\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noserlight.ch\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/#organization\",\"name\":\"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\",\"url\":\"https:\/\/www.noserlight.ch\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2022\/12\/NoserlightAG_Logo_mit_Schlirgg_NEU_1-1.png\",\"contentUrl\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2022\/12\/NoserlightAG_Logo_mit_Schlirgg_NEU_1-1.png\",\"width\":482,\"height\":121,\"caption\":\"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\"},\"image\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/noserlight\/\",\"https:\/\/www.instagram.com\/noserlight\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/#\/schema\/person\/cd72adab091f0db04aef8e43d9b74611\",\"name\":\"Nosi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b18cc96158a2073e0df080a95bd309c904e62cb170d71914b5ddd7d9292afb82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b18cc96158a2073e0df080a95bd309c904e62cb170d71914b5ddd7d9292afb82?s=96&d=mm&r=g\",\"caption\":\"Nosi\"},\"url\":\"https:\/\/www.noserlight.ch\/home\/author\/nosi\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einbruchschutz - Licht schreckt ab - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/","og_locale":"de_DE","og_type":"article","og_title":"Einbruchschutz - Licht schreckt ab - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","og_description":"F\u00fcr eine zus\u00e4tzliche Sicherheitsbeleuchtung werden zum Beispiel unter dem Dachfirst Strahler oder Scheinwerfer montiert. Mit mehreren Bewegungsmeldern verbunden und in einer Reihe geschaltet oder mit anderen elektronischen Sicherheitseinrichtungen kombiniert, sollten sie den Bereich rund ums Haus m\u00f6glichst l\u00fcckenlos ausleuchten.","og_url":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/","og_site_name":"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","article_publisher":"https:\/\/www.facebook.com\/noserlight\/","article_published_time":"2025-07-10T15:11:47+00:00","article_modified_time":"2025-07-17T23:08:47+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg","type":"image\/jpeg"}],"author":"Nosi","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Nosi","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#article","isPartOf":{"@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/"},"author":{"name":"Nosi","@id":"https:\/\/www.noserlight.ch\/home\/#\/schema\/person\/cd72adab091f0db04aef8e43d9b74611"},"headline":"Einbruchschutz &#8211; Licht schreckt ab","datePublished":"2025-07-10T15:11:47+00:00","dateModified":"2025-07-17T23:08:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/"},"wordCount":1291,"publisher":{"@id":"https:\/\/www.noserlight.ch\/home\/#organization"},"image":{"@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg","keywords":["LED Aussenbeleuchtung","LED Aussenlampen","LED Bewegungsmelder","LED Einbruchschutz","LED Fluter","LED Flutlicht","LED f\u00fcr Aussen","LED Hallenbeleuchtung","LED Parkplatzbeleuchtung","LED Platzbeleuchtung","LED Strahler","LED Strahler mit abnehmbarem Akku","LED Strahler mit Bewegungsmelder","LED Strahler mit Powerbank","LED Strahler mit Sensor","LED Strahler mobil"],"articleSection":["Architectural Lighting","Facility Lighting","Home Lighting - Licht f\u00fcr Zuhause","NOSER","Professionelle LED Beleuchtung","Tipps und Tricks"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/","url":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/","name":"Einbruchschutz - Licht schreckt ab - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","isPartOf":{"@id":"https:\/\/www.noserlight.ch\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#primaryimage"},"image":{"@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg","datePublished":"2025-07-10T15:11:47+00:00","dateModified":"2025-07-17T23:08:47+00:00","breadcrumb":{"@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#primaryimage","url":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg","contentUrl":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.noserlight.ch\/home\/einbruchschutz-ploetzliches-licht-schreckt-ab-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.noserlight.ch\/home\/"},{"@type":"ListItem","position":2,"name":"Einbruchschutz &#8211; Licht schreckt ab"}]},{"@type":"WebSite","@id":"https:\/\/www.noserlight.ch\/home\/#website","url":"https:\/\/www.noserlight.ch\/home\/","name":"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","description":"Bruchsch Liecht? D\u00e4 Nosi h\u00e4t&#039;s!","publisher":{"@id":"https:\/\/www.noserlight.ch\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noserlight.ch\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.noserlight.ch\/home\/#organization","name":"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","url":"https:\/\/www.noserlight.ch\/home\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.noserlight.ch\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2022\/12\/NoserlightAG_Logo_mit_Schlirgg_NEU_1-1.png","contentUrl":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2022\/12\/NoserlightAG_Logo_mit_Schlirgg_NEU_1-1.png","width":482,"height":121,"caption":"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung"},"image":{"@id":"https:\/\/www.noserlight.ch\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noserlight\/","https:\/\/www.instagram.com\/noserlight\/"]},{"@type":"Person","@id":"https:\/\/www.noserlight.ch\/home\/#\/schema\/person\/cd72adab091f0db04aef8e43d9b74611","name":"Nosi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.noserlight.ch\/home\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b18cc96158a2073e0df080a95bd309c904e62cb170d71914b5ddd7d9292afb82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18cc96158a2073e0df080a95bd309c904e62cb170d71914b5ddd7d9292afb82?s=96&d=mm&r=g","caption":"Nosi"},"url":"https:\/\/www.noserlight.ch\/home\/author\/nosi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/posts\/23752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/comments?post=23752"}],"version-history":[{"count":0,"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/posts\/23752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/media\/27151"}],"wp:attachment":[{"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/media?parent=23752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/categories?post=23752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/wp-json\/wp\/v2\/tags?post=23752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}