{"id":27306,"date":"2024-10-04T16:41:48","date_gmt":"2024-10-04T14:41:48","guid":{"rendered":"https:\/\/www.noserlight.ch\/home\/il-dimmer-intelligente-per-tutte-le-situazioni\/"},"modified":"2024-02-10T20:13:41","modified_gmt":"2024-02-10T19:13:41","slug":"il-dimmer-intelligente-per-tutte-le-situazioni","status":"publish","type":"post","link":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/","title":{"rendered":"Il dimmer intelligente per tutte le situazioni"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;37&#8243; padding_bottom=&#8221;37&#8243; css=&#8221;.vc_custom_1706294129640{background-color: #ffffff !important;}&#8221; z_index=&#8221;&#8221;][vc_column][vc_column_text]La gamma di apparecchi e sorgenti luminose dimmerabili che utilizzano la tecnologia LED sta diventando sempre pi\u00f9 ampia e confusa. Ci sono anche sempre pi\u00f9 apparecchi che possono essere dimmerati solo in modo insoddisfacente o, nel peggiore dei casi, non possono essere dimmerati affatto con i dimmer tradizionali. Il nuovo dimmer universale OmnioUPD230\/10 di AWAG offre una soluzione. La terza generazione di questo collaudato dimmer basato sulla tecnologia wireless EnOcean \u00e8 stata completamente rivista e progettata appositamente per i moderni apparecchi LED. Alla prima accensione, il dimmer analizza automaticamente il carico collegato e avvia un processo di calibrazione. I parametri di regolazione ottimali risultanti vengono memorizzati in modo permanente sul dispositivo.[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"wpaicg-chat-shortcode-content\">\n<p><span id=\"wpaicg-chat-message-74707\" class=\"wpaicg-chat-message\">Naturalmente! L&#8217;illuminazione del tavolo da pranzo svolge un ruolo importante nel creare un&#8217;atmosfera piacevole e allo stesso tempo avere luce sufficiente per mangiare e intrattenersi. Esistono vari modi per illuminare il tavolo da pranzo. Ecco alcune cose da tenere d&#8217;occhio.<\/span><\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221; padding_top=&#8221;37&#8243; padding_bottom=&#8221;37&#8243; background_color=&#8221;#ffffff&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><a itemprop=\"url\" href=\"https:\/\/www.omnio.ch\/fileadmin\/dateien\/pdf\/Fachbeitrag_Omnio_Dimmer.pdf\" target=\"\" class=\"q_icon_link\"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-book qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/a><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">KNOW-HOW<\/h3><p style='color: #000000'><\/p><a itemprop='url' class='icon_with_title_link' href='https:\/\/www.omnio.ch\/fileadmin\/dateien\/pdf\/Fachbeitrag_Omnio_Dimmer.pdf' target='_self' style=''>Leggi qui le informazioni specializzate<\/a><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/LEDInfo\/NOSERLIGHT_Omnio_Deutsch_2019_web.pdf\" target=\"\" class=\"q_icon_link\"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-download qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/a><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">DOWNLOAD<\/h3><p style=''><\/p><a itemprop='url' class='icon_with_title_link' href='https:\/\/www.noserlight.ch\/LEDInfo\/NOSERLIGHT_Omnio_Deutsch_2019_web.pdf' target='_self' style=''>Scarica qui il catalogo OMNIO<\/a><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221; padding_top=&#8221;37&#8243; padding_bottom=&#8221;37&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h5><a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_RatgeberLEDErsatzT5T8Sparlampen.pdf\" target=\"_blank\" rel=\"noopener\">GUIDA DIVIETO DI LAMPADE<\/a><br \/>\n<a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_RatgeberLEDErsatzT5T8Sparlampen.pdf\" target=\"_blank\" rel=\"noopener\">LAMPADE E TUBI A RISPARMIO ENERGETICO<\/a><\/h5>\n<p>[\/vc_column_text][vc_separator type=&#8221;normal&#8221;][vc_empty_space][vc_single_image image=&#8221;17949&#8243; img_size=&#8221;600&#215;600&#8243; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; qode_css_animation=&#8221;&#8221; qode_hover_animation=&#8221;darken&#8221; link=&#8221;https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_RatgeberLEDErsatzT5T8Sparlampen.pdf&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h5><a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHTRatgeberLEDErsatzHalogen.pdf\" target=\"_blank\" rel=\"noopener\">GUIDA DIVIETO DI LAMPADE<\/a><br \/>\n<a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHTRatgeberLEDErsatzHalogen.pdf\" target=\"_blank\" rel=\"noopener\">LAMPADE AD ALOGENO<\/a><\/h5>\n<p>[\/vc_column_text][vc_separator type=&#8221;normal&#8221;][vc_empty_space][vc_single_image image=&#8221;18433&#8243; img_size=&#8221;600&#215;600&#8243; onclick=&#8221;custom_link&#8221; qode_css_animation=&#8221;&#8221; qode_hover_animation=&#8221;darken&#8221; link=&#8221;https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHTRatgeberLEDErsatzHalogen.pdf&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h5><a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LED_Leuchtmittel.pdf\">TUTTI I LED<br \/>\nLAMPADINE E TUBI<\/a><\/h5>\n<p>[\/vc_column_text][vc_separator type=&#8221;normal&#8221;][vc_empty_space][vc_single_image image=&#8221;18409&#8243; img_size=&#8221;600&#215;600&#8243; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; qode_css_animation=&#8221;&#8221; qode_hover_animation=&#8221;darken&#8221; link=&#8221;https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LED_Leuchtmittel.pdf&#8221;][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;37&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h5><a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LED_HalogenRetrofit_Leuchtmittel.pdf\" target=\"_blank\" rel=\"noopener\">LED PER LA SOSTITUZIONE <\/a><br \/>\n<a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LED_HalogenRetrofit_Leuchtmittel.pdf\" target=\"_blank\" rel=\"noopener\">LAMPADE AD ALOGENO<\/a><\/h5>\n<p>[\/vc_column_text][vc_separator type=&#8221;normal&#8221;][vc_empty_space][vc_single_image image=&#8221;25820&#8243; img_size=&#8221;600&#215;600&#8243; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; qode_css_animation=&#8221;&#8221; qode_hover_animation=&#8221;darken&#8221; link=&#8221;https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_LED_HalogenRetrofit_Leuchtmittel.pdf&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h5><a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_RatgeberLEDErsatzT5T8Sparlampen.pdf\" target=\"_blank\" rel=\"noopener\">LED PER LA SOSTITUZIONE<\/a><br \/>\n<a href=\"https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_RatgeberLEDErsatzT5T8Sparlampen.pdf\" target=\"_blank\" rel=\"noopener\">LAMPADE E TUBI A RISPARMIO ENERGETICO<\/a><\/h5>\n<p>[\/vc_column_text][vc_separator type=&#8221;normal&#8221;][vc_empty_space][vc_single_image image=&#8221;26461&#8243; img_size=&#8221;600&#215;600&#8243; onclick=&#8221;custom_link&#8221; qode_css_animation=&#8221;&#8221; qode_hover_animation=&#8221;darken&#8221; link=&#8221;https:\/\/noserlight.ch\/LEDInfo\/NOSERLIGHT_RatgeberLEDErsatzT5T8Sparlampen.pdf&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h5><a href=\"https:\/\/www.noserlight.ch\/shop\/de\/led-leuchtmittel\" target=\"_blank\" rel=\"noopener\">VEDERE LE CATEGORIE <\/a><br \/>\n<a href=\"https:\/\/www.noserlight.ch\/shop\/de\/led-leuchtmittel\" target=\"_blank\" rel=\"noopener\">DEL NEGOZIO ONLINE<\/a><\/h5>\n<p>[\/vc_column_text][vc_separator type=&#8221;normal&#8221;][vc_empty_space][vc_single_image image=&#8221;25828&#8243; img_size=&#8221;600&#215;600&#8243; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; qode_css_animation=&#8221;&#8221; qode_hover_animation=&#8221;darken&#8221; link=&#8221;https:\/\/noserlight.ch\/shop&#8221;][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;57&#8243; padding_bottom=&#8221;57&#8243; css=&#8221;.vc_custom_1706294549018{background-color: #ffffff !important;}&#8221; z_index=&#8221;&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">ATTUALE<\/h2>\n<p>[\/vc_column_text][vc_separator type=&#8221;small&#8221; position=&#8221;center&#8221; down=&#8221;45&#8243; up=&#8221;7&#8243;]\n<div class='latest_post_holder boxes three_columns three_rows' >\n    <ul>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/sostituto-dei-tubi-fluorescenti-e-delle-lampade-a-risparmio-energetico\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"292\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/02\/ID111_LED_T8_Kat-539x292.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/sostituto-dei-tubi-fluorescenti-e-delle-lampade-a-risparmio-energetico\/\">SOSTITUTO DEI TUBI FLUORESCENTI E DELLE LAMPADE A RISPARMIO ENERGETICO<\/a><\/h5>\n                            <p class=\"excerpt\">Stai cercando un sostituto per le lampade a risparmio energetico e i tubi FL che sono stati banditi? Ve lo offriamo. Sia...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/luce-per-sentieri-e-scale-esterne\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-300x169.jpg 300w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-1024x576.jpg 1024w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-768x432.jpg 768w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-1536x864.jpg 1536w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen-700x394.jpg 700w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGH_LEDAussenbeleuchtungWegeTreppen.jpg 1920w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/luce-per-sentieri-e-scale-esterne\/\">Luce per sentieri e scale esterne<\/a><\/h5>\n                            <p class=\"excerpt\">Illuminazione di sentieri e scale. I percorsi verso e intorno alla casa, l'ingresso della cantina o il garage devono ess...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/protezione-antieffrazione-la-luce-e-un-deterrente\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-300x169.jpg 300w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-1024x576.jpg 1024w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-768x432.jpg 768w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-1536x864.jpg 1536w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter-700x394.jpg 700w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/NOSERLIGHT_LEDStrahler_LEDFluter.jpg 1920w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/protezione-antieffrazione-la-luce-e-un-deterrente\/\">Protezione antieffrazione: la luce \u00e8 un deterrente<\/a><\/h5>\n                            <p class=\"excerpt\">Per un'illuminazione di sicurezza aggiuntiva, i faretti o i proiettori vengono montati, ad esempio, sotto il colmo del t...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/classi-di-protezione\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/IP_Schutzarten637x320-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/IP_Schutzarten637x320-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/10\/IP_Schutzarten637x320-570x320.jpg 570w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/classi-di-protezione\/\">Classi di protezione<\/a><\/h5>\n                            <p class=\"excerpt\">APPARECCHI E CLASSI DI PROTEZIONE\nIn elettrotecnica, le classi di protezione sono utilizzate per classificare e identifi...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/benvenuti-luce-per-lingresso-della-casa\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/03\/NOSERLIGHT_LichtfuerdenEingang-2-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/benvenuti-luce-per-lingresso-della-casa\/\">Benvenuti! Luce per l&#8217;ingresso della casa<\/a><\/h5>\n                            <p class=\"excerpt\">La luce nell&#8217;area d&#8217;ingresso e sulla porta d&#8217;ingresso \u00e8 doppiamente importante: \u00e8 invitante e fornisce...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/raggiungere-limpatto-della-luce-ambientale\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" srcset=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-539x303.jpg 539w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-300x169.jpg 300w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-1024x576.jpg 1024w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-768x432.jpg 768w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-1536x864.jpg 1536w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V-700x394.jpg 700w, https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/09\/NOSERLIGHT_LEDStrip240V.jpg 1920w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/raggiungere-limpatto-della-luce-ambientale\/\">Ottenere l&#8217;effetto (luce ambientale)!<\/a><\/h5>\n                            <p class=\"excerpt\">Poich\u00e9 la luce indiretta brilla in modo diffuso, non proietta ombre, si distribuisce in modo ottimale nell'ambiente e no...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/la-finestra-luminosa-intelligente\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/02\/NOSERLIGHT_LEDPanelOffice-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/la-finestra-luminosa-intelligente\/\">La finestra luminosa intelligente<\/a><\/h5>\n                            <p class=\"excerpt\">I pannelli luminosi a LED sono diventati un argomento di attualit\u00e0. I nostri pannelli LED......<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/suggerimenti-per-la-progettazione-dellilluminazione-privata\/\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"303\" src=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2023\/02\/suite_ambient-980x500-1-539x303.jpg\" class=\"attachment-latest_post_boxes size-latest_post_boxes wp-post-image\" alt=\"\" \/><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/suggerimenti-per-la-progettazione-dellilluminazione-privata\/\">Suggerimenti per la progettazione dell&#8217;illuminazione privata<\/a><\/h5>\n                            <p class=\"excerpt\">Mangiare, leggere, guardare la TV, lavorare o rilassarsi: l&#8217;esempio del soggiorno dimostra che l&#8217;illuminazio...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n    \n        <li class=\"clearfix\">\n            <div class=\"boxes_image\">\n                                <a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/yano-il-mix-perfetto-di-giocosita-e-precisione\/\"><\/a>\n            <\/div>\n            <div class=\"latest_post\"  >\n                <div class=\"latest_post_text\">\n                    <div class=\"latest_post_inner\">\n                        <div class=\"latest_post_text_inner\">\n                            <h5 itemprop=\"name\" class=\"latest_post_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.noserlight.ch\/home\/it\/yano-il-mix-perfetto-di-giocosita-e-precisione\/\">YANO. Il mix perfetto di giocosit\u00e0 e precisione.<\/a><\/h5>\n                            <p class=\"excerpt\">La lampada YANO di OLIGO Lichttechnik \u00e8 composta da due anelli sospesi separatamente, la cui distanza tra loro \u00e8 variabi...<\/p>\n                            <span class=\"post_infos\">\n                                                                                                \n                                \n                                                            <\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/li>\n        <\/ul>\n<\/div>[\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221; padding_top=&#8221;57&#8243;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">CONTATTO<\/h2>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_separator type=&#8221;small&#8221; position=&#8221;center&#8221; down=&#8221;38&#8243; up=&#8221;7&#8243;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;20&#8243; padding_bottom=&#8221;57&#8243; z_index=&#8221;&#8221;][vc_column width=&#8221;1\/4&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-clock-o qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">ORARIO DI APERTURA<\/h3><p style=''><\/p><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Lu. &#8211; Ven.<br \/>\n<\/strong>07.30 &#8211; 12.00, 13.15 &#8211; 17.30<br \/>\n<strong>Sab. <\/strong>09.00 &#8211; 16.00, senza interruzione<\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;30px&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-home qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">VISITACI<\/h3><p style=''><\/p><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\"> Scopri i nostri prodotti<br \/>\nOttenbacherstrasse 25<br \/>\nCH-8909 Zwillikon\/Affoltern a.A.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;30px&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-phone qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">CHIAMACI O SCRIVICI<\/h3><p style=''><\/p><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\">Phone: +41 44 701 81 81<br \/>\nEmail: <a href=\"mailto:info@noserlight.ch.ch\">info@noserlight.ch.ch<\/a><\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;30px&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;]<div class='q_icon_with_title medium circle center '><div class=\"icon_holder \" style=\"margin: 0 0 28px 0; \"><span data-icon-type=\"circle\" data-icon-hover-color=\"#ffff00\" data-icon-hover-bg-color=\"#ffffff\" class=\"qode_iwt_icon_holder fa-stack fa-3x  \" style=\"font-size: 45px;border-color: #000000;background-color: #000000;\"><i class=\"qode_icon_font_awesome fa fa-thumbs-o-up qode_iwt_icon_element\" style=\"color: #ffffff;\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"\">SEGUICI<\/h3><p style=''><\/p><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\">Instagram: <a href=\"https:\/\/www.instagram.com\/noserlight\/\">@noserlight.ch<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/noserlight\/\">Facebook: Bruchsch Liecht?<\/a><\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;30px&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;57&#8243; padding_bottom=&#8221;37&#8243; z_index=&#8221;&#8221; background_color=&#8221;#ffffff&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">SLOW SOCIAL<\/h2>\n<h3 style=\"text-align: center;\"> SERVIZIO PERSONALIZZATO<br \/>\nNELLA NOSTRA GRANDE ESPOSIZIONE A LED<\/h3>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_separator type=&#8221;small&#8221; position=&#8221;center&#8221; down=&#8221;38&#8243; up=&#8221;7&#8243;][vc_gmaps link=&#8221;#E-8_JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxMW0xOCUyMTFtMTIlMjExbTMlMjExZDI3MDYuMzIwNzA5NTcxMTA4NiUyMTJkOC40MzkxODIzMTU4NTE0MjclMjEzZDQ3LjI4ODUzMTk3OTE2NDk0JTIxMm0zJTIxMWYwJTIxMmYwJTIxM2YwJTIxM20yJTIxMWkxMDI0JTIxMmk3NjglMjE0ZjEzLjElMjEzbTMlMjExbTIlMjExczB4NDc5MDA2MThlMzI1OTZiNSUyNTNBMHgyN2JmNmNkMmI5MjdkMWUlMjEyc05vc2VyJTI1MjBMaWdodCUyNTIwQUclMjE1ZTAlMjEzbTIlMjExc2RlJTIxMnNjaCUyMTR2MTY3Mzc4OTQwMzg0MCUyMTVtMiUyMTFzZGUlMjEyc2NoJTIyJTIwd2lkdGglM0QlMjI2MDAlMjIlMjBoZWlnaHQlM0QlMjI0NTAlMjIlMjBzdHlsZSUzRCUyMmJvcmRlciUzQTAlM0IlMjIlMjBhbGxvd2Z1bGxzY3JlZW4lM0QlMjIlMjIlMjBsb2FkaW5nJTNEJTIybGF6eSUyMiUyMHJlZmVycmVycG9saWN5JTNEJTIybm8tcmVmZXJyZXItd2hlbi1kb3duZ3JhZGUlMjIlM0UlM0MlMkZpZnJhbWUlM0U=&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;grid&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; z_index=&#8221;&#8221; padding_top=&#8221;20&#8243; padding_bottom=&#8221;20&#8243;][vc_column css=&#8221;.vc_custom_1699039779113{background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221;][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">NEWS \/ SOCIAL MEDIA<\/h2>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_separator type=&#8221;small&#8221; position=&#8221;center&#8221; down=&#8221;38&#8243; up=&#8221;7&#8243;][vc_column_text css=&#8221;.vc_custom_1699045234277{background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221;]        <div\n            class=\"spotlight-instagram-feed\"\n            data-feed-var=\"cd839c3e\"\n            data-analytics=\"1\"\n            data-instance=\"24097\"\n        >\n        <\/div>\n        <input type=\"hidden\" id=\"sli__f__cd839c3e\" data-json='{&quot;useCase&quot;:&quot;accounts&quot;,&quot;template&quot;:&quot;gallery&quot;,&quot;layout&quot;:&quot;grid&quot;,&quot;numColumns&quot;:{&quot;desktop&quot;:3,&quot;tablet&quot;:3,&quot;phone&quot;:3},&quot;highlightFreq&quot;:{&quot;desktop&quot;:7},&quot;sliderNumScrollPosts&quot;:{&quot;desktop&quot;:1},&quot;sliderInfinite&quot;:true,&quot;sliderLoop&quot;:false,&quot;sliderArrowPos&quot;:{&quot;desktop&quot;:&quot;inside&quot;},&quot;sliderArrowSize&quot;:{&quot;desktop&quot;:20},&quot;sliderArrowColor&quot;:{&quot;r&quot;:255,&quot;b&quot;:255,&quot;g&quot;:255,&quot;a&quot;:1},&quot;sliderArrowBgColor&quot;:{&quot;r&quot;:0,&quot;b&quot;:0,&quot;g&quot;:0,&quot;a&quot;:0.8000000000000000444089209850062616169452667236328125},&quot;sliderAutoScroll&quot;:false,&quot;sliderAutoInterval&quot;:3,&quot;postOrder&quot;:&quot;date_desc&quot;,&quot;numPosts&quot;:{&quot;desktop&quot;:6,&quot;tablet&quot;:9,&quot;phone&quot;:9},&quot;linkBehavior&quot;:{&quot;desktop&quot;:&quot;new_tab&quot;},&quot;feedWidth&quot;:{&quot;desktop&quot;:0},&quot;feedHeight&quot;:{&quot;desktop&quot;:&quot;&quot;},&quot;feedPadding&quot;:{&quot;desktop&quot;:0,&quot;tablet&quot;:0,&quot;phone&quot;:0},&quot;imgPadding&quot;:{&quot;desktop&quot;:7,&quot;tablet&quot;:7,&quot;phone&quot;:6},&quot;ratio&quot;:&quot;classic&quot;,&quot;textSize&quot;:{&quot;desktop&quot;:&quot;&quot;,&quot;tablet&quot;:&quot;&quot;,&quot;phone&quot;:&quot;&quot;},&quot;bgColor&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:255,&quot;a&quot;:0},&quot;hoverInfo&quot;:[&quot;likes_comments&quot;,&quot;insta_link&quot;],&quot;textColorHover&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:255,&quot;a&quot;:1},&quot;bgColorHover&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:0.5},&quot;showHeader&quot;:{&quot;desktop&quot;:false},&quot;headerInfo&quot;:{&quot;desktop&quot;:[&quot;profile_pic&quot;,&quot;bio&quot;],&quot;phone&quot;:[&quot;profile_pic&quot;,&quot;bio&quot;]},&quot;headerAccount&quot;:5,&quot;headerStyle&quot;:{&quot;desktop&quot;:&quot;normal&quot;,&quot;phone&quot;:&quot;centered&quot;},&quot;headerTextSize&quot;:{&quot;desktop&quot;:&quot;&quot;},&quot;headerPhotoSize&quot;:{&quot;desktop&quot;:50},&quot;headerTextColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;headerBgColor&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:255,&quot;a&quot;:1},&quot;headerPadding&quot;:{&quot;desktop&quot;:2},&quot;customProfilePic&quot;:0,&quot;customBioText&quot;:&quot;&quot;,&quot;includeStories&quot;:false,&quot;storiesInterval&quot;:5,&quot;showCaptions&quot;:{&quot;desktop&quot;:false,&quot;tablet&quot;:false,&quot;phone&quot;:false},&quot;captionMaxLength&quot;:{&quot;desktop&quot;:0},&quot;captionRemoveDots&quot;:false,&quot;captionSize&quot;:{&quot;desktop&quot;:0},&quot;captionColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;showLikes&quot;:{&quot;desktop&quot;:false},&quot;showComments&quot;:{&quot;desktop&quot;:false},&quot;lcIconSize&quot;:{&quot;desktop&quot;:14},&quot;likesIconColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;commentsIconColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;lightboxShowSidebar&quot;:false,&quot;lightboxCtaStyle&quot;:&quot;link&quot;,&quot;lightboxCtaDesign&quot;:{&quot;text&quot;:{&quot;color&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;align&quot;:&quot;center&quot;},&quot;bgColor&quot;:{&quot;r&quot;:230,&quot;g&quot;:230,&quot;b&quot;:230,&quot;a&quot;:1},&quot;border&quot;:{&quot;radius&quot;:3}},&quot;numLightboxComments&quot;:50,&quot;showLoadMoreBtn&quot;:{&quot;desktop&quot;:true},&quot;loadMoreBtnDesign&quot;:{&quot;text&quot;:{&quot;color&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:0,&quot;a&quot;:1},&quot;align&quot;:&quot;center&quot;},&quot;border&quot;:{&quot;radius&quot;:10},&quot;bgColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;margin&quot;:{&quot;top&quot;:0,&quot;bottom&quot;:0,&quot;left&quot;:0,&quot;right&quot;:0}},&quot;loadMoreBtnText&quot;:&quot;Load more&quot;,&quot;loadMoreBtnScroll&quot;:true,&quot;autoload&quot;:false,&quot;showFollowBtn&quot;:{&quot;desktop&quot;:true,&quot;phone&quot;:false,&quot;tablet&quot;:false},&quot;followBtnText&quot;:&quot;Follow us&quot;,&quot;followBtnDesign&quot;:{&quot;text&quot;:{&quot;color&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;align&quot;:&quot;center&quot;},&quot;border&quot;:{&quot;radius&quot;:1},&quot;bgColor&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:0,&quot;a&quot;:1},&quot;margin&quot;:{&quot;top&quot;:0,&quot;bottom&quot;:0,&quot;left&quot;:0,&quot;right&quot;:0}},&quot;followBtnLocation&quot;:{&quot;desktop&quot;:&quot;header&quot;,&quot;phone&quot;:&quot;bottom&quot;},&quot;alignFooterButtons&quot;:{&quot;desktop&quot;:true},&quot;customCss&quot;:&quot;\\\/* Enter your custom CSS below *\\\/\\n\\n&quot;,&quot;accounts&quot;:[28981],&quot;tagged&quot;:[],&quot;hashtags&quot;:[],&quot;mediaType&quot;:&quot;all&quot;,&quot;hashtagWhitelist&quot;:[],&quot;hashtagBlacklist&quot;:[],&quot;captionWhitelist&quot;:[],&quot;captionBlacklist&quot;:[],&quot;hashtagWhitelistSettings&quot;:true,&quot;hashtagBlacklistSettings&quot;:true,&quot;captionWhitelistSettings&quot;:true,&quot;captionBlacklistSettings&quot;:true,&quot;moderation&quot;:[],&quot;moderationMode&quot;:&quot;blacklist&quot;,&quot;promosVersion&quot;:2,&quot;promosEnabled&quot;:true,&quot;globalPromosEnabled&quot;:true,&quot;autoPromosEnabled&quot;:true,&quot;promoOverrides&quot;:[],&quot;feedPromo&quot;:{&quot;linkSource&quot;:{&quot;type&quot;:null},&quot;linkBehavior&quot;:{&quot;openNewTab&quot;:false,&quot;showPopupBox&quot;:false},&quot;linkText&quot;:&quot;&quot;},&quot;gaCampaignSource&quot;:&quot;&quot;,&quot;gaCampaignMedium&quot;:&quot;&quot;,&quot;gaCampaignName&quot;:&quot;&quot;}' \/>\n        <input type=\"hidden\" id=\"sli__a__cd839c3e\" data-json='[{&quot;id&quot;:28981,&quot;type&quot;:&quot;PERSONAL&quot;,&quot;userId&quot;:&quot;9015409761892929&quot;,&quot;username&quot;:&quot;noserlight&quot;,&quot;bio&quot;:&quot;&quot;,&quot;customBio&quot;:&quot;\\&quot;Bruchsch Liecht?\\&quot;\\ud83d\\udca1\\n\\nLightstyle. Sustainability. Knowhow.\\n\\&quot;D\\u00e4 Nosi h\\u00e4t&#039;s!\\&quot;\\n\\n\\ud83c\\udf0d Online\\n\\ud83d\\udc41 &gt;300m2 Walk-in Ausstellung &amp; Store \\ud83d\\udecd\\n.\\n\\ud83d\\udc47\\ud83d\\udc47\\ud83d\\udc47\\ud83d\\udc47\\ud83d\\udc47\\nOttenbacherstr. 25, Affoltern am Albis, Switzerland 8909&quot;,&quot;profilePicUrl&quot;:&quot;&quot;,&quot;customProfilePicUrl&quot;:&quot;https:\\\/\\\/www.noserlight.ch\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NoserlightIGLogo.jpg&quot;,&quot;mediaCount&quot;:&quot;231&quot;,&quot;followersCount&quot;:&quot;0&quot;,&quot;usages&quot;:[],&quot;creationDate&quot;:&quot;2025-08-11 09:04:49&quot;}]' \/>\n        <input type=\"hidden\" id=\"sli__m__cd839c3e\" data-json='[]' \/>\n        [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La gamma di apparecchi e sorgenti luminose dimmerabili che utilizzano la tecnologia LED sta diventando sempre pi\u00f9 ampia e confusa. Ci sono anche sempre pi\u00f9 apparecchi che possono essere dimmerati solo in modo insoddisfacente o, nel peggiore dei casi, non possono essere dimmerati affatto con i dimmer tradizionali.<\/p>\n","protected":false},"author":1,"featured_media":26934,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[1884,1702],"tags":[2874,2875,2873,2872,1127,2878,1600,2877],"class_list":["post-27306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli-e-suggerimenti","category-led-know-how-it","tag-automazione-degli-edifici","tag-installazione-elettrica-intelligente","tag-linstallazione-elettrica-intelligente","tag-led-dimmerabili","tag-omnio","tag-sistema-di-automazione-degli-edifici","tag-smart-led","tag-un-dimmer-per-tutte-le-situazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Il dimmer intelligente per tutte le situazioni - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Il dimmer intelligente per tutte le situazioni - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\" \/>\r\n<meta property=\"og:description\" content=\"La gamma di apparecchi e sorgenti luminose dimmerabili che utilizzano la tecnologia LED sta diventando sempre pi\u00f9 ampia e confusa. Ci sono anche sempre pi\u00f9 apparecchi che possono essere dimmerati solo in modo insoddisfacente o, nel peggiore dei casi, non possono essere dimmerati affatto con i dimmer tradizionali.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noserlight\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-10-04T14:41:48+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Lighty\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lighty\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/\"},\"author\":{\"name\":\"Lighty\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/person\/818b9e4797c2714379883d5a5f1a86df\"},\"headline\":\"Il dimmer intelligente per tutte le situazioni\",\"datePublished\":\"2024-10-04T14:41:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/\"},\"wordCount\":1574,\"publisher\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg\",\"keywords\":[\"Automazione degli edifici\",\"Installazione elettrica intelligente\",\"L'installazione elettrica intelligente\",\"led dimmerabili\",\"Omnio\",\"Sistema di automazione degli edifici\",\"smart led\",\"Un dimmer per tutte le situazioni\"],\"articleSection\":[\"Consigli e suggerimenti\",\"LED Know-How\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/\",\"url\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/\",\"name\":\"Il dimmer intelligente per tutte le situazioni - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\",\"isPartOf\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg\",\"datePublished\":\"2024-10-04T14:41:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#primaryimage\",\"url\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg\",\"contentUrl\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.noserlight.ch\/home\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il dimmer intelligente per tutte le situazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#website\",\"url\":\"https:\/\/www.noserlight.ch\/home\/it\/\",\"name\":\"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\",\"description\":\"Bruchsch Liecht? D\u00e4 Nosi h\u00e4t&#039;s!\",\"publisher\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noserlight.ch\/home\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#organization\",\"name\":\"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\",\"url\":\"https:\/\/www.noserlight.ch\/home\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2022\/12\/NoserlightAG_Logo_mit_Schlirgg_NEU_1-1.png\",\"contentUrl\":\"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2022\/12\/NoserlightAG_Logo_mit_Schlirgg_NEU_1-1.png\",\"width\":482,\"height\":121,\"caption\":\"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung\"},\"image\":{\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/noserlight\/\",\"https:\/\/www.instagram.com\/noserlight\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/person\/818b9e4797c2714379883d5a5f1a86df\",\"name\":\"Lighty\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/989f9fa74ba285c67e97f07f3b90258a3543e7fadbafa214115603a49797ac7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/989f9fa74ba285c67e97f07f3b90258a3543e7fadbafa214115603a49797ac7a?s=96&d=mm&r=g\",\"caption\":\"Lighty\"},\"sameAs\":[\"https:\/\/www.noserlight.ch\/home\/\"],\"url\":\"https:\/\/www.noserlight.ch\/home\/it\/author\/lighty\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il dimmer intelligente per tutte le situazioni - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/","og_locale":"it_IT","og_type":"article","og_title":"Il dimmer intelligente per tutte le situazioni - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","og_description":"La gamma di apparecchi e sorgenti luminose dimmerabili che utilizzano la tecnologia LED sta diventando sempre pi\u00f9 ampia e confusa. Ci sono anche sempre pi\u00f9 apparecchi che possono essere dimmerati solo in modo insoddisfacente o, nel peggiore dei casi, non possono essere dimmerati affatto con i dimmer tradizionali.","og_url":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/","og_site_name":"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","article_publisher":"https:\/\/www.facebook.com\/noserlight\/","article_published_time":"2024-10-04T14:41:48+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg","type":"image\/jpeg"}],"author":"Lighty","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Lighty","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#article","isPartOf":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/"},"author":{"name":"Lighty","@id":"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/person\/818b9e4797c2714379883d5a5f1a86df"},"headline":"Il dimmer intelligente per tutte le situazioni","datePublished":"2024-10-04T14:41:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/"},"wordCount":1574,"publisher":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/#organization"},"image":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg","keywords":["Automazione degli edifici","Installazione elettrica intelligente","L'installazione elettrica intelligente","led dimmerabili","Omnio","Sistema di automazione degli edifici","smart led","Un dimmer per tutte le situazioni"],"articleSection":["Consigli e suggerimenti","LED Know-How"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/","url":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/","name":"Il dimmer intelligente per tutte le situazioni - Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","isPartOf":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#primaryimage"},"image":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg","datePublished":"2024-10-04T14:41:48+00:00","breadcrumb":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#primaryimage","url":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg","contentUrl":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2021\/10\/NOSERLIGHT_LEDDimmer.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.noserlight.ch\/home\/it\/il-dimmer-intelligente-per-tutte-le-situazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.noserlight.ch\/home\/it\/"},{"@type":"ListItem","position":2,"name":"Il dimmer intelligente per tutte le situazioni"}]},{"@type":"WebSite","@id":"https:\/\/www.noserlight.ch\/home\/it\/#website","url":"https:\/\/www.noserlight.ch\/home\/it\/","name":"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","description":"Bruchsch Liecht? D\u00e4 Nosi h\u00e4t&#039;s!","publisher":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noserlight.ch\/home\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.noserlight.ch\/home\/it\/#organization","name":"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung","url":"https:\/\/www.noserlight.ch\/home\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2022\/12\/NoserlightAG_Logo_mit_Schlirgg_NEU_1-1.png","contentUrl":"https:\/\/www.noserlight.ch\/home\/wp-content\/uploads\/2022\/12\/NoserlightAG_Logo_mit_Schlirgg_NEU_1-1.png","width":482,"height":121,"caption":"Noserlight AG, LED Leuchten und LED Lampen, LED, Licht, Lichtplanung"},"image":{"@id":"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noserlight\/","https:\/\/www.instagram.com\/noserlight\/"]},{"@type":"Person","@id":"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/person\/818b9e4797c2714379883d5a5f1a86df","name":"Lighty","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.noserlight.ch\/home\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/989f9fa74ba285c67e97f07f3b90258a3543e7fadbafa214115603a49797ac7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/989f9fa74ba285c67e97f07f3b90258a3543e7fadbafa214115603a49797ac7a?s=96&d=mm&r=g","caption":"Lighty"},"sameAs":["https:\/\/www.noserlight.ch\/home\/"],"url":"https:\/\/www.noserlight.ch\/home\/it\/author\/lighty\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/posts\/27306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/comments?post=27306"}],"version-history":[{"count":0,"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/posts\/27306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/media\/26934"}],"wp:attachment":[{"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/media?parent=27306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/categories?post=27306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noserlight.ch\/home\/it\/wp-json\/wp\/v2\/tags?post=27306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}